<br />
<b>Deprecated</b>:  Method ReflectionParameter::getClass() is deprecated in <b>/home/cbqaglob/public_html/wp-content/plugins/cred-frontend-editor/vendor/toolset/toolset-common/lib/auryn/lib/CachingReflector.php</b> on line <b>89</b><br />
{"id":1615,"date":"2022-06-30T07:58:46","date_gmt":"2022-06-30T07:58:46","guid":{"rendered":"https:\/\/www.cbqaglobal.com\/validation\/?post_type=training&#038;p=1615"},"modified":"2022-06-30T07:58:46","modified_gmt":"2022-06-30T07:58:46","slug":"hanggara-ragil-putranto","status":"publish","type":"training","link":"https:\/\/www.cbqaglobal.com\/validation\/training\/hanggara-ragil-putranto\/","title":{"rendered":"Hanggara Ragil Putranto"},"content":{"rendered":"","protected":false},"template":"","_links":{"self":[{"href":"https:\/\/www.cbqaglobal.com\/validation\/wp-json\/wp\/v2\/training\/1615"}],"collection":[{"href":"https:\/\/www.cbqaglobal.com\/validation\/wp-json\/wp\/v2\/training"}],"about":[{"href":"https:\/\/www.cbqaglobal.com\/validation\/wp-json\/wp\/v2\/types\/training"}],"wp:attachment":[{"href":"https:\/\/www.cbqaglobal.com\/validation\/wp-json\/wp\/v2\/media?parent=1615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}