<br />
<b>Deprecated</b>:  Method ReflectionParameter::getClass() is deprecated in <b>/home/cbqaglob/public_html/wp-content/plugins/cred-frontend-editor/vendor/toolset/toolset-common/lib/auryn/lib/CachingReflector.php</b> on line <b>89</b><br />
{"id":2922,"date":"2023-03-14T02:21:52","date_gmt":"2023-03-14T02:21:52","guid":{"rendered":"https:\/\/www.cbqaglobal.com\/validation\/?post_type=training&#038;p=2922"},"modified":"2023-03-14T02:21:52","modified_gmt":"2023-03-14T02:21:52","slug":"benedick-yansen-junior","status":"publish","type":"training","link":"https:\/\/www.cbqaglobal.com\/validation\/training\/benedick-yansen-junior\/","title":{"rendered":"Benedick Yansen Junior"},"content":{"rendered":"","protected":false},"template":"","_links":{"self":[{"href":"https:\/\/www.cbqaglobal.com\/validation\/wp-json\/wp\/v2\/training\/2922"}],"collection":[{"href":"https:\/\/www.cbqaglobal.com\/validation\/wp-json\/wp\/v2\/training"}],"about":[{"href":"https:\/\/www.cbqaglobal.com\/validation\/wp-json\/wp\/v2\/types\/training"}],"wp:attachment":[{"href":"https:\/\/www.cbqaglobal.com\/validation\/wp-json\/wp\/v2\/media?parent=2922"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}